{"id":275,"count":115,"description":"","link":"https:\/\/besunet.com\/entamenews\/category\/%e6%87%90%e3%81%8b%e3%81%97%e3%81%ae%e3%82%a2%e3%82%a4%e3%83%89%e3%83%ab%e3%83%bb%e3%82%b9%e3%82%bf%e3%83%bc%e3%80%81%e3%83%9f%e3%83%a5%e3%83%bc%e3%82%b8%e3%82%b7%e3%83%a3%e3%83%b3","name":"\u61d0\u304b\u3057\u306e\u30a2\u30a4\u30c9\u30eb\u30fb\u30b9\u30bf\u30fc\u3001\u30df\u30e5\u30fc\u30b8\u30b7\u30e3\u30f3","slug":"%e6%87%90%e3%81%8b%e3%81%97%e3%81%ae%e3%82%a2%e3%82%a4%e3%83%89%e3%83%ab%e3%83%bb%e3%82%b9%e3%82%bf%e3%83%bc%e3%80%81%e3%83%9f%e3%83%a5%e3%83%bc%e3%82%b8%e3%82%b7%e3%83%a3%e3%83%b3","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/besunet.com\/entamenews\/wp-json\/wp\/v2\/categories\/275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/besunet.com\/entamenews\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/besunet.com\/entamenews\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/besunet.com\/entamenews\/wp-json\/wp\/v2\/posts?categories=275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}