{"id":2109,"count":1,"description":"","link":"https:\/\/besunet.com\/entamenews\/tag\/%e3%83%ad%e3%83%bc%e3%83%a9-%e6%9c%ac%e5%90%8d","name":"\u30ed\u30fc\u30e9 \u672c\u540d","slug":"%e3%83%ad%e3%83%bc%e3%83%a9-%e6%9c%ac%e5%90%8d","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/besunet.com\/entamenews\/wp-json\/wp\/v2\/tags\/2109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/besunet.com\/entamenews\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/besunet.com\/entamenews\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/besunet.com\/entamenews\/wp-json\/wp\/v2\/posts?tags=2109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}